{"id":5127,"date":"2022-06-24T18:38:03","date_gmt":"2022-06-24T16:38:03","guid":{"rendered":"https:\/\/lloseta.com\/?page_id=5127"},"modified":"2025-07-15T15:55:36","modified_gmt":"2025-07-15T13:55:36","slug":"oratori-del-coco","status":"publish","type":"page","link":"https:\/\/lloseta.com\/es\/patrimonio\/oratori-del-coco\/","title":{"rendered":"Oratori del Coc\u00f3"},"content":{"rendered":"<div  class=\"tatsu-HkI7YLv99 tatsu-section    tatsu-clearfix\" data-title=\"\"  data-headerscheme=\"background--light\"><div class='tatsu-section-pad clearfix' data-padding='{\"d\":\"0px 0% 0px 0%\"}' data-padding-top='0px'><div class=\"tatsu-row-wrap  tatsu-row-full-width tatsu-row-has-one-half tatsu-row-has-two-cols tatsu-zero-margin tatsu-no-gutter tatsu-eq-cols  tatsu-clearfix tatsu-HylI7K8Pcq\" ><div  class=\"tatsu-row \" ><div  class=\"tatsu-column  tatsu-column-empty tatsu-one-half tatsu-column-align-middle tatsu-column-image-none tatsu-column-effect-none  tatsu-Sk-I7tLP9q\"  data-parallax-speed=\"0\" style=\"\"><div class=\"tatsu-column-inner \" ><div class=\"tatsu-column-pad-wrap\"><div class=\"tatsu-column-pad\" ><\/div><\/div><div class = \"tatsu-column-bg-image-wrap\"><div class = \"tatsu-column-bg-image\" ><\/div><\/div><\/div><style>.tatsu-row > .tatsu-Sk-I7tLP9q.tatsu-column{width: 50%;}.tatsu-Sk-I7tLP9q.tatsu-column > .tatsu-column-inner > .tatsu-column-bg-image-wrap > .tatsu-column-bg-image{background-image: url(https:\/\/lloseta.com\/wp-content\/uploads\/2022\/06\/lloseta-coco-coco-coco.jpg);background-repeat: no-repeat;background-attachment: scroll;background-position: top center;background-size: cover;}.tatsu-Sk-I7tLP9q.tatsu-column > .tatsu-column-inner > .tatsu-bg-blur{background-repeat: no-repeat;background-attachment: scroll;background-position: top center;background-size: cover;}.tatsu-Sk-I7tLP9q.tatsu-column > .tatsu-column-inner > .tatsu-column-pad-wrap > .tatsu-column-pad{padding: 10% 15% 10% 15%;}.tatsu-Sk-I7tLP9q.tatsu-column > .tatsu-column-inner > .tatsu-column-overlay{mix-blend-mode: none;}.tatsu-Sk-I7tLP9q > .tatsu-column-inner > .tatsu-top-divider{z-index: 9999;}.tatsu-Sk-I7tLP9q > .tatsu-column-inner > .tatsu-bottom-divider{z-index: 9999;}.tatsu-Sk-I7tLP9q > .tatsu-column-inner > .tatsu-left-divider{z-index: 9999;}.tatsu-Sk-I7tLP9q > .tatsu-column-inner > .tatsu-right-divider{z-index: 9999;}@media only screen and (max-width: 767px) {.tatsu-row > .tatsu-Sk-I7tLP9q.tatsu-column{width: 100%;}}<\/style><\/div><div  class=\"tatsu-column  tatsu-one-half tatsu-column-align-middle tatsu-column-image-none tatsu-column-effect-none  tatsu-S1fL7YLwqq\"  data-parallax-speed=\"0\" style=\"\"><div class=\"tatsu-column-inner \" ><div class=\"tatsu-column-pad-wrap\"><div class=\"tatsu-column-pad\" ><div  class=\"tatsu-module tatsu-title-icon  tatsu-rJm87KIP55  \" ><span class=\"tatsu-ti-wrap tatsu-ti medium plain align-left\" ><i class=\"fa fa-home tatsu-ti tatsu-ti-icon\"><\/i><\/span><div class=\"tatsu-tc tatsu-tc-custom-space align-left medium plain\">\n<h4>Oratori del Coc\u00f3<\/h4>\n<\/div><style>.tatsu-rJm87KIP55 .tatsu-ti-icon{color: #FF9800 ;}.tatsu-rJm87KIP55{margin: 0 0 0px 0;padding: 50px 0px 20px 0px;}<\/style><\/div><div  class=\"tatsu-module tatsu-text-block-wrap tatsu-Hk4U7K8vqq  \"><div class=\"tatsu-text-inner tatsu-align-center  clearfix\" ><style>.tatsu-Hk4U7K8vqq.tatsu-text-block-wrap .tatsu-text-inner{width: 100%;text-align: left;}<\/style>\n<p><span id=\"result_box\" class=\"\" lang=\"es\"><span title=\"El promotor d'aquest oratori fou el vicari de Lloseta Miquel Arbona Mayol.\">El promotor de este oratorio fue\u00a0el vicario de Lloseta Miquel Arbona Mayol.\u00a0<\/span><span title=\"El 20 de novembre de 1876 va fer la petici\u00f3 de construcci\u00f3 de L'oratori al bisbe de Mallorca amb la finalitat de fomentar el culte a la Mare de D\u00e9u de Lloseta. \">El 20 de noviembre de 1876 hizo la petici\u00f3n de construcci\u00f3n de El oratorio al obispo de Mallorca con el fin de fomentar el culto a la Virgen de Lloseta.<\/span><\/span><\/p>\n<p><span title=\"El 1877 s'iniciaren les obres sent el mestre d'obres i foren acabades totalment el juny de 1878 malgrat que I'oratori ja havia estat bene\u00eft el mes d'abril. \">En 1877 se iniciaron las obras siendo el maestro de obras y fueron terminadas totalmente en junio de 1878 a pesar de que I\u2019oratori ya hab\u00eda sido bendecido el mes de abril.<\/span><\/p>\n<p><span title=\"L'oratori consta d'una sola nau de dimensions redu\u00efdes -nou per quatre metres-, amb de volta d'aresta i un retaule on hi ha la imatge de la Mare de D\u00e9u.\">El oratorio\u00a0consta de una sola nave de dimensiones reducidas\u00a0-nueve por cuatro metros-, con b\u00f3veda de arista y un retablo donde est\u00e1 la imagen de la Virgen.\u00a0<\/span><span title=\"A la part de darrera es troba la sagristia. \">En la parte trasera se encuentra la sacrist\u00eda.<\/span><\/p>\n<p><span title=\"L'edifici fou reformat 1978 l'any del seu centenari.\">El edificio fue reformado 1.978 el a\u00f1o de su centenario.\u00a0<\/span><span title=\"La imatge antiga, obra de Serra retirada l'any 1974 i avui es conserva a la sagristia de l' esgl\u00e9sia parroquial. \">La imagen antigua, obra de Serra retirada en 1974 y hoy se conserva en la sacrist\u00eda de la iglesia parroquial.<\/span><\/p>\n<p><span title=\"La nova \u00e9s obra de I'escultor Francesc Salva i \u00e9s una copia de I'autentica.\">La nueva\u00a0es obra de el escultor Francisco Salva y es una copia de la autentica.\u00a0<\/span><span title=\"En els anys 1974-75, es pinta el retaule de color mar\u00e8s, es renov\u00e0 tota la teulada, a la capella es feren els baixos de pedra i es recuper\u00e0 I'antic mar\u00e8s de la volta.\">En los a\u00f1os 1974-75, se pinta el retablo de color arenisca, se renov\u00f3 todo el tejado, en la capilla se hicieron los bajos de piedra y se recuper\u00f3 el antiguo arenisca de la b\u00f3veda.\u00a0<\/span><span title=\"Fora de la capella s'ampli\u00e0 el recinte.\">Fuera de la capilla se ampli\u00f3 el recinto.\u00a0<\/span><span title=\"El 1988 fou declarat B\u00e9 d'lnteres Cultural.\">En 1988 fue declarado Bien de lnteres Cultural.<\/span><\/p>\n<\/div><\/div><div  class=\"tatsu-module tatsu-normal-button tatsu-button-wrap   tatsu-Bk9Sf5IPqq   \"><a class=\"tatsu-shortcode mediumbtn tatsu-button left-icon circular  mfp-iframe bg-animation-none  \" href=\"https:\/\/lloseta.com\/wp-content\/uploads\/2025\/07\/coco.mp4\" style= \"\"  aria-label=\"Ver v\u00eddeo\" data-gdpr-atts={} ><i class=\"tatsu-icon tatsu-icon-video2\"><\/i>Ver v\u00eddeo<\/a><style>.tatsu-Bk9Sf5IPqq .tatsu-button{background-color: #FF9800;color: #ffffff ;}<\/style><\/div><\/div><\/div><div class = \"tatsu-column-bg-image-wrap\"><div class = \"tatsu-column-bg-image\" ><\/div><\/div><\/div><style>.tatsu-row > .tatsu-S1fL7YLwqq.tatsu-column{width: 50%;}.tatsu-S1fL7YLwqq.tatsu-column > .tatsu-column-inner{background-color: rgba(255,255,255,1);}.tatsu-S1fL7YLwqq.tatsu-column > .tatsu-column-inner > .tatsu-column-pad-wrap > .tatsu-column-pad{padding: 10% 15% 10% 15%;}.tatsu-S1fL7YLwqq.tatsu-column > .tatsu-column-inner > .tatsu-column-overlay{mix-blend-mode: none;}.tatsu-S1fL7YLwqq > .tatsu-column-inner > .tatsu-top-divider{z-index: 9999;}.tatsu-S1fL7YLwqq > .tatsu-column-inner > .tatsu-bottom-divider{z-index: 9999;}.tatsu-S1fL7YLwqq > .tatsu-column-inner > .tatsu-left-divider{z-index: 9999;}.tatsu-S1fL7YLwqq > .tatsu-column-inner > .tatsu-right-divider{z-index: 9999;}@media only screen and (max-width: 767px) {.tatsu-row > .tatsu-S1fL7YLwqq.tatsu-column{width: 100%;}}<\/style><\/div><\/div><\/div><\/div><div class=\"tatsu-section-background-wrap\"><div class = \"tatsu-section-background\" ><\/div><\/div><style>.tatsu-HkI7YLv99{border-width: 0px 0px px 0px;border-style: solid;}.tatsu-HkI7YLv99 .tatsu-section-pad{padding: 0px 0% 0px 0%;}.tatsu-HkI7YLv99 > .tatsu-bottom-divider{z-index: 9999;}.tatsu-HkI7YLv99 > .tatsu-top-divider{z-index: 9999;}<\/style><\/div><div  class=\"tatsu-r1rL7YLvcc tatsu-section    tatsu-clearfix\" data-title=\"\"  data-headerscheme=\"background--light\"><div class='tatsu-section-pad clearfix' data-padding='{\"d\":\"20px 0% 20px 0%\"}' data-padding-top='20px'><div class=\"tatsu-row-wrap  tatsu-wrap tatsu-row-one-col tatsu-row-has-one-cols tatsu-medium-gutter tatsu-reg-cols  tatsu-clearfix tatsu-SJL8mYLw5q\" ><div  class=\"tatsu-row \" ><div  class=\"tatsu-column  tatsu-column-no-bg tatsu-one-col tatsu-column-image-none tatsu-column-effect-none  tatsu-H1DLXYLwq5\"  data-parallax-speed=\"0\" style=\"\"><div class=\"tatsu-column-inner \" ><div class=\"tatsu-column-pad-wrap\"><div class=\"tatsu-column-pad\" ><div  class=\"tatsu-module tatsu-call-to-action tatsu-clearfix  tatsu-HkOLmKLD59  \" ><div class=\"tatsu-cta-inner\"><h5 class=\"tatsu-action-content\" >\u00bfQUIERES CONOCER EL PATRIMONIO DE LLOSETA?<\/h5><a class=\"mediumbtn tatsu-button rounded tatsu-action-button   \" href=\"\/es\/patrimoni\" data-gdpr-atts={} ><span>LLOSETA MONUMENTAL<\/span><\/a><style>.tatsu-HkOLmKLD59.tatsu-call-to-action{background-color: #222222;}.tatsu-HkOLmKLD59 .tatsu-action-content{color: rgba(255,255,255,1) ;}.tatsu-HkOLmKLD59 .tatsu-action-button{background: #FF9800;border-color: #FF9800; }.tatsu-HkOLmKLD59 .tatsu-action-button:hover{background: #ffffff;border-color: #000000; }.tatsu-HkOLmKLD59 .tatsu-action-button span{color: rgba(255,255,255,1) ;}.tatsu-HkOLmKLD59 .tatsu-action-button:hover span{color: #FF9800 ;}<\/style><\/div><\/div><\/div><\/div><div class = \"tatsu-column-bg-image-wrap\"><div class = \"tatsu-column-bg-image\" ><\/div><\/div><\/div><style>.tatsu-row > .tatsu-H1DLXYLwq5.tatsu-column{width: 100%;}.tatsu-H1DLXYLwq5.tatsu-column > .tatsu-column-inner > .tatsu-column-overlay{mix-blend-mode: none;}.tatsu-H1DLXYLwq5 > .tatsu-column-inner > .tatsu-top-divider{z-index: 9999;}.tatsu-H1DLXYLwq5 > .tatsu-column-inner > .tatsu-bottom-divider{z-index: 9999;}.tatsu-H1DLXYLwq5 > .tatsu-column-inner > .tatsu-left-divider{z-index: 9999;}.tatsu-H1DLXYLwq5 > .tatsu-column-inner > .tatsu-right-divider{z-index: 9999;}<\/style><\/div><\/div><\/div><\/div><div class=\"tatsu-section-background-wrap\"><div class = \"tatsu-section-background\" ><\/div><\/div><style>.tatsu-r1rL7YLvcc.tatsu-section{background-color: #222222;}.tatsu-r1rL7YLvcc{border-width: 0px 0px px 0px;border-style: solid;}.tatsu-r1rL7YLvcc .tatsu-section-pad{padding: 20px 0% 20px 0%;}.tatsu-r1rL7YLvcc > .tatsu-bottom-divider{z-index: 9999;}.tatsu-r1rL7YLvcc > .tatsu-top-divider{z-index: 9999;}<\/style><\/div>\n","protected":false},"excerpt":{"rendered":"<p><a href=\"https:\/\/lloseta.com\/es\/patrimonio\/oratori-del-coco\/\" class=\"more-link style2-button\">Read More<\/a><\/p>","protected":false},"author":1,"featured_media":0,"parent":5110,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-5127","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/lloseta.com\/es\/wp-json\/wp\/v2\/pages\/5127","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lloseta.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lloseta.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lloseta.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lloseta.com\/es\/wp-json\/wp\/v2\/comments?post=5127"}],"version-history":[{"count":8,"href":"https:\/\/lloseta.com\/es\/wp-json\/wp\/v2\/pages\/5127\/revisions"}],"predecessor-version":[{"id":6298,"href":"https:\/\/lloseta.com\/es\/wp-json\/wp\/v2\/pages\/5127\/revisions\/6298"}],"up":[{"embeddable":true,"href":"https:\/\/lloseta.com\/es\/wp-json\/wp\/v2\/pages\/5110"}],"wp:attachment":[{"href":"https:\/\/lloseta.com\/es\/wp-json\/wp\/v2\/media?parent=5127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}