{"id":5992,"date":"2022-06-30T07:00:27","date_gmt":"2022-06-30T05:00:27","guid":{"rendered":"https:\/\/lloseta.com\/?p=5992"},"modified":"2022-06-30T09:48:26","modified_gmt":"2022-06-30T07:48:26","slug":"lloseta-sera-punto-de-paso-y-partida-de-la-tradicional-marcha-des-guell-a-lluc-a-peu","status":"publish","type":"post","link":"https:\/\/lloseta.com\/es\/2022\/06\/30\/lloseta-sera-punto-de-paso-y-partida-de-la-tradicional-marcha-des-guell-a-lluc-a-peu\/","title":{"rendered":"Lloseta ser\u00e1 punto de paso y partida de la tradicional marcha Des G\u00fcell a Lluc a Peu"},"content":{"rendered":"<p>Lloseta ser\u00e1<strong> punto de paso y tambi\u00e9n de partida de la La 48\u00aa marcha Des G\u00fcell a Lluc a Peu que tendr\u00e1 lugar finalmente el pr\u00f3ximo 6 de agosto<\/strong> sin restricciones por la pandemia.<\/p>\n<p>Esta tradicional celebraci\u00f3n <strong>siempre ha tenido a Lloseta como punto de paso de los miles de caminantes que participan en el evento.<\/strong> Adem\u00e1s, Lloseta tambi\u00e9n ser\u00e1 punto de partida para los que quieran iniciar la caminata desde nuestra localidad.<\/p>\n<p>La marcha Des G\u00fcell a Lluc a Peu<strong> no s\u00f3lo es un s\u00edmbolo de mallorquinidad, sino que tambi\u00e9n permite hacer deporte, socializar y disfrutar de la naturaleza<\/strong> en compa\u00f1\u00eda celebrando la vuelta a la normalidad. En Lloseta, como siempre, estamos encantados de recibir a los miles de participantes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lloseta ser\u00e1 punto de paso y tambi\u00e9n de partida de la La 48\u00aa marcha Des G\u00fcell a Lluc a Peu que tendr\u00e1 lugar finalmente el pr\u00f3ximo 6 de agosto sin [&hellip;]<\/p>\n<p><a href=\"https:\/\/lloseta.com\/es\/2022\/06\/30\/lloseta-sera-punto-de-paso-y-partida-de-la-tradicional-marcha-des-guell-a-lluc-a-peu\/\" class=\"more-link style2-button\">Read More<\/a><\/p>","protected":false},"author":1,"featured_media":5944,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[86],"tags":[],"class_list":["post-5992","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-del-pueblo"],"acf":[],"_links":{"self":[{"href":"https:\/\/lloseta.com\/es\/wp-json\/wp\/v2\/posts\/5992","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lloseta.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lloseta.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lloseta.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lloseta.com\/es\/wp-json\/wp\/v2\/comments?post=5992"}],"version-history":[{"count":1,"href":"https:\/\/lloseta.com\/es\/wp-json\/wp\/v2\/posts\/5992\/revisions"}],"predecessor-version":[{"id":5995,"href":"https:\/\/lloseta.com\/es\/wp-json\/wp\/v2\/posts\/5992\/revisions\/5995"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lloseta.com\/es\/wp-json\/wp\/v2\/media\/5944"}],"wp:attachment":[{"href":"https:\/\/lloseta.com\/es\/wp-json\/wp\/v2\/media?parent=5992"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lloseta.com\/es\/wp-json\/wp\/v2\/categories?post=5992"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lloseta.com\/es\/wp-json\/wp\/v2\/tags?post=5992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}