{"id":6067,"date":"2022-06-30T12:48:21","date_gmt":"2022-06-30T10:48:21","guid":{"rendered":"https:\/\/lloseta.com\/?p=6067"},"modified":"2022-06-30T12:56:39","modified_gmt":"2022-06-30T10:56:39","slug":"lloseta-exporta-calidad-al-extranjero","status":"publish","type":"post","link":"https:\/\/lloseta.com\/es\/2022\/06\/30\/lloseta-exporta-calidad-al-extranjero\/","title":{"rendered":"Lloseta exporta calidad al extranjero"},"content":{"rendered":"<p>Varias empresas de Lloseta<strong> no solo han conseguido asentarse en Mallorca sino que tambi\u00e9n han logrado expandirse al resto de Espa\u00f1a y al extranjero.<\/strong> Este es el caso de <a href=\"https:\/\/lloseta.com\/es\/comercos\/bestard-mountain-boots\/\">Calzados Bestard<\/a> y <a href=\"https:\/\/lloseta.com\/es\/comercos\/teixits-riera\/\">Teixits Riera<\/a> que han logrado un merecido prestigio internacional dada la alta calidad de sus productos.<\/p>\n<p>Bestard <strong>fue fundada en el a\u00f1o 1940 en el coraz\u00f3n de Lloseta,<\/strong> lugar donde todav\u00eda mantiene la f\u00e1brica y gran parte de la producci\u00f3n de botas de monta\u00f1a. Bestard cuenta con una extensa red comercial en Espa\u00f1a y en Europa, Am\u00e9rica, Asia y Ocean\u00eda.<\/p>\n<p>Seg\u00fan su sitio web oficial su distribuci\u00f3n<strong> se extiende a pa\u00edses tan lejanos y variados como Chipre, Polonia, Suecia, Chile, Colombia, M\u00e9xico, Estados Unidos, Australia, China, Ir\u00e1n, Singapur, Malasia o Taiwan.<\/strong><\/p>\n<p>Por su lado, <strong>Teixits Riera se dedica al dise\u00f1o y fabricaci\u00f3n de telas<\/strong> desde hace casi 125 a\u00f1os. Su pasi\u00f3n y creatividad en la creaci\u00f3n del emblem\u00e1tico #IkatFromMallorca, y <strong>su respeto por los procedimientos artesanales y la aplicaci\u00f3n de los conocimientos heredados de generaciones predecesoras tambi\u00e9n les ha valido el reconocimiento internacional.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Varias empresas de Lloseta no solo han conseguido asentarse en Mallorca sino que tambi\u00e9n han logrado expandirse al resto de Espa\u00f1a y al extranjero. Este es el caso de Calzados [&hellip;]<\/p>\n<p><a href=\"https:\/\/lloseta.com\/es\/2022\/06\/30\/lloseta-exporta-calidad-al-extranjero\/\" class=\"more-link style2-button\">Read More<\/a><\/p>","protected":false},"author":1,"featured_media":6064,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[161],"tags":[],"class_list":["post-6067","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comercio"],"acf":[],"_links":{"self":[{"href":"https:\/\/lloseta.com\/es\/wp-json\/wp\/v2\/posts\/6067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lloseta.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lloseta.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lloseta.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lloseta.com\/es\/wp-json\/wp\/v2\/comments?post=6067"}],"version-history":[{"count":2,"href":"https:\/\/lloseta.com\/es\/wp-json\/wp\/v2\/posts\/6067\/revisions"}],"predecessor-version":[{"id":6079,"href":"https:\/\/lloseta.com\/es\/wp-json\/wp\/v2\/posts\/6067\/revisions\/6079"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lloseta.com\/es\/wp-json\/wp\/v2\/media\/6064"}],"wp:attachment":[{"href":"https:\/\/lloseta.com\/es\/wp-json\/wp\/v2\/media?parent=6067"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lloseta.com\/es\/wp-json\/wp\/v2\/categories?post=6067"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lloseta.com\/es\/wp-json\/wp\/v2\/tags?post=6067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}